{"id":552,"date":"2021-03-08T14:16:25","date_gmt":"2021-03-08T14:16:25","guid":{"rendered":"http:\/\/www2.outbrain.com\/resources\/?post_type=webinars&#038;p=552"},"modified":"2026-07-20T11:12:56","modified_gmt":"2026-07-20T11:12:56","slug":"outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads","status":"publish","type":"webinars","link":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/","title":{"rendered":"Naked Wines Success Story: The &#8220;Wine-In&#8221; Consumer Experience &#038; Native Ads"},"content":{"rendered":"","protected":false},"featured_media":554,"template":"","meta":{"_acf_changed":false,"footnotes":""},"product":[2],"vertical":[4],"topics":[18],"class_list":["post-552","webinars","type-webinars","status-publish","has-post-thumbnail","hentry","product-advertisers","vertical-general","topics-app-install"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.9 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Naked Wines Success Story: The &quot;Wine-In&quot; Consumer Experience &amp; Native Ads - Resources<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Naked Wines Success Story: The &quot;Wine-In&quot; Consumer Experience &amp; Native Ads - Resources\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/\" \/>\n<meta property=\"og:site_name\" content=\"Resources\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/outbrain\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T11:12:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.outbrain.com\/resources\/wp-content\/uploads\/2021\/03\/Group-2-Copy-12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"523\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@outbrain\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/\",\"url\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/\",\"name\":\"Naked Wines Success Story: The \\\"Wine-In\\\" Consumer Experience & Native Ads - Resources\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Group-2-Copy-12.png\",\"datePublished\":\"2021-03-08T14:16:25+00:00\",\"dateModified\":\"2026-07-20T11:12:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Group-2-Copy-12.png\",\"contentUrl\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Group-2-Copy-12.png\",\"width\":523,\"height\":295,\"caption\":\"hosts\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/webinars\\\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Webinars\",\"item\":\"https:\\\/\\\/www3.outbrain.com\\\/resources\\\/webinars\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Naked Wines Success Story: The &#8220;Wine-In&#8221; Consumer Experience &#038; Native Ads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/#website\",\"url\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/\",\"name\":\"Resources\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.outbrain.com\\\/resources\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Naked Wines Success Story: The \"Wine-In\" Consumer Experience & Native Ads - Resources","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/","og_locale":"en_US","og_type":"article","og_title":"Naked Wines Success Story: The \"Wine-In\" Consumer Experience & Native Ads - Resources","og_url":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/","og_site_name":"Resources","article_publisher":"https:\/\/www.facebook.com\/outbrain","article_modified_time":"2026-07-20T11:12:56+00:00","og_image":[{"width":523,"height":295,"url":"https:\/\/www.outbrain.com\/resources\/wp-content\/uploads\/2021\/03\/Group-2-Copy-12.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@outbrain","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/","url":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/","name":"Naked Wines Success Story: The \"Wine-In\" Consumer Experience & Native Ads - Resources","isPartOf":{"@id":"https:\/\/www.outbrain.com\/resources\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/#primaryimage"},"image":{"@id":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/#primaryimage"},"thumbnailUrl":"https:\/\/www.outbrain.com\/resources\/wp-content\/uploads\/2021\/03\/Group-2-Copy-12.png","datePublished":"2021-03-08T14:16:25+00:00","dateModified":"2026-07-20T11:12:56+00:00","breadcrumb":{"@id":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/#primaryimage","url":"https:\/\/www.outbrain.com\/resources\/wp-content\/uploads\/2021\/03\/Group-2-Copy-12.png","contentUrl":"https:\/\/www.outbrain.com\/resources\/wp-content\/uploads\/2021\/03\/Group-2-Copy-12.png","width":523,"height":295,"caption":"hosts"},{"@type":"BreadcrumbList","@id":"https:\/\/www.outbrain.com\/resources\/webinars\/outbrain-and-naked-wines-success-story-the-wine-in-consumer-experience-native-ads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Webinars","item":"https:\/\/www3.outbrain.com\/resources\/webinars\/"},{"@type":"ListItem","position":2,"name":"Naked Wines Success Story: The &#8220;Wine-In&#8221; Consumer Experience &#038; Native Ads"}]},{"@type":"WebSite","@id":"https:\/\/www.outbrain.com\/resources\/#website","url":"https:\/\/www.outbrain.com\/resources\/","name":"Resources","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.outbrain.com\/resources\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/webinars\/552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/webinars"}],"about":[{"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/types\/webinars"}],"version-history":[{"count":1,"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/webinars\/552\/revisions"}],"predecessor-version":[{"id":5467,"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/webinars\/552\/revisions\/5467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/media\/554"}],"wp:attachment":[{"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/media?parent=552"}],"wp:term":[{"taxonomy":"product","embeddable":true,"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/product?post=552"},{"taxonomy":"vertical","embeddable":true,"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/vertical?post=552"},{"taxonomy":"topics","embeddable":true,"href":"https:\/\/www.outbrain.com\/resources\/wp-json\/wp\/v2\/topics?post=552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}